{"id":1751,"date":"2024-06-05T20:54:29","date_gmt":"2024-06-05T18:54:29","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1751"},"modified":"2024-10-06T13:32:41","modified_gmt":"2024-10-06T11:32:41","slug":"graduacion-2023-2024","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/","title":{"rendered":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria"},"content":{"rendered":"\n<p>\u00a1\u00a1Ya tenemos organizado la entrega de becas para la graduaci\u00f3n de 3\u00ba de Infantil y 6\u00ba de Primaria!!<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<!--more-->\n\n\n\n<p>Os esperamos<strong> el d\u00eda 20 de junio en el Centro C\u00edvico \u00abLa Buhaira\u00bb a las 20:00 horas<\/strong> para entregar las becas y el diploma acreditativo del fin de ciclo.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si las familias quer\u00e9is preparar con los peques alguna actuaci\u00f3n, estar\u00e1 preparado un escenario y con el equipo de sonido que nos llevaremos desde la AMPA.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>\u00a1\u00a1Est\u00e1is todas las familias invitadas al acto!!<\/strong><\/p>\n\n\n\n<div style=\"height:62px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/GRADUACION-SAN-BERNADRO-3o-DE-INFANTIL-Y-6o-PRIMARIA-1.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"1752\" src=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/GRADUACION-SAN-BERNADRO-3o-DE-INFANTIL-Y-6o-PRIMARIA-1-724x1024.jpg\" alt=\"\" class=\"wp-image-1752\"\/><\/a><\/figure>\n<\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-4-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-4-576x1024.jpg\" alt=\"\" class=\"wp-image-1772\" style=\"width:305px;height:auto\"\/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d12681.182800951121!2d-5.9787299!3d37.3828387!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd126ea423a2f873%3A0x2640b9875a3e656c!2sCentro%20C%C3%ADvico%20Buhaira%20(Palacio%20Neomud%C3%A9jar%20con%20restos%20almohades)!5e0!3m2!1ses!2ses!4v1717660738628!5m2!1ses!2ses\" width=\"756\" height=\"360\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u00a1\u00a1AY\u00daDANOS A CRECER COMO AMPA!!<\/strong>&nbsp;<strong>\u00a1\u00a1As\u00f3ciate a la AMPA!!<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\">Por una cuota de 35\u20ac anuales por familia, mejora tu colegio, conoce informaci\u00f3n \u00fatil como esta y obt\u00e9n beneficios y descuentos.<\/a><\/strong>&nbsp;<a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/strong><\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tambi\u00e9n puedes participar, a trav\u00e9s del voluntariado, apoyando las actividades que desarrollamos o planteando nuevas ideas que quieras poner en marcha junto a nuestro equipo.<\/a><\/strong>\u00a0<strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/a><\/strong><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1\u00a1Ya tenemos organizado la entrega de becas para la graduaci\u00f3n de 3\u00ba de Infantil y 6\u00ba de Primaria!!<\/p>\n","protected":false},"author":1,"featured_media":1765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[43,62,63,30],"class_list":["post-1751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-curso-2023-24","tag-fin-de-curso","tag-graduacion","tag-tiempo-libre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"og:description\" content=\"\u00a1\u00a1Ya tenemos organizado la entrega de becas para la graduaci\u00f3n de 3\u00ba de Infantil y 6\u00ba de Primaria!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T18:54:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-06T11:32:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1363\" \/>\n\t<meta property=\"og:image:height\" content=\"938\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria\",\"datePublished\":\"2024-06-05T18:54:29+00:00\",\"dateModified\":\"2024-10-06T11:32:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/\"},\"wordCount\":167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg\",\"keywords\":[\"Curso 2023\\\/24\",\"Fin de curso\",\"Graduaci\u00f3n\",\"Tiempo libre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/\",\"name\":\"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg\",\"datePublished\":\"2024-06-05T18:54:29+00:00\",\"dateModified\":\"2024-10-06T11:32:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg\",\"width\":1363,\"height\":938},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2024\\\/06\\\/05\\\/graduacion-2023-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla","og_description":"\u00a1\u00a1Ya tenemos organizado la entrega de becas para la graduaci\u00f3n de 3\u00ba de Infantil y 6\u00ba de Primaria!!","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2024-06-05T18:54:29+00:00","article_modified_time":"2024-10-06T11:32:41+00:00","og_image":[{"width":1363,"height":938,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria","datePublished":"2024-06-05T18:54:29+00:00","dateModified":"2024-10-06T11:32:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/"},"wordCount":167,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg","keywords":["Curso 2023\/24","Fin de curso","Graduaci\u00f3n","Tiempo libre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/","name":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg","datePublished":"2024-06-05T18:54:29+00:00","dateModified":"2024-10-06T11:32:41+00:00","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2024\/06\/invitacion-fiesta-de-egresados-ninos-infantil-colorido-436-x-300-px.jpg","width":1363,"height":938},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2024\/06\/05\/graduacion-2023-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"Acto de graduaci\u00f3n 3\u00ba infantil y 6\u00ba primaria"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1751"}],"version-history":[{"count":18,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions"}],"predecessor-version":[{"id":1919,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions\/1919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1765"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}