{"id":1696,"date":"2023-10-30T13:02:25","date_gmt":"2023-10-30T12:02:25","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1696"},"modified":"2024-06-06T10:32:30","modified_gmt":"2024-06-06T08:32:30","slug":"nuevo-telefono-ampa","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/","title":{"rendered":"Nuevo tel\u00e9fono de la AMPA"},"content":{"rendered":"\n<p>Tras diversos problemas con el proveedor de telefon\u00eda m\u00f3vil, nos hemos visto obligadas a cambiar de n\u00famero para seguir atendi\u00e9ndoos como siempre a trav\u00e9s de WhatsApp o llamada de tel\u00e9fono (esperamos que el nuevo n\u00famero est\u00e9 activo antes del 1 de noviembre de 2023). Mientras&#8230; <strong>\u00a1Apunta el nuevo n\u00famero&#8230; y perdona si no has podido contactar con nosotras! <\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"has-text-align-center has-large-font-size\"><strong>+(34) 614 137 234<\/strong><\/p>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u00a1\u00a1AY\u00daDANOS A CRECER COMO AMPA!!<\/strong>&nbsp;<strong>\u00a1\u00a1As\u00f3ciate!!<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\">Por una cuota de 35\u20ac anuales por familia, mejora tu colegio, conoce informaci\u00f3n \u00fatil como esta y obt\u00e9n beneficios y descuentos.<\/a><\/strong>&nbsp;<a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/strong><\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tambi\u00e9n puedes participar, a trav\u00e9s del voluntariado, apoyando las actividades que desarrollamos o planteando nuevas ideas que quieras poner en marcha junto a nuestro equipo.<\/a><\/strong>&nbsp;<strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/a><\/strong><\/p>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras diversos problemas con el proveedor de telefon\u00eda m\u00f3vil, nos hemos visto obligadas a cambiar de n\u00famero para seguir atendi\u00e9ndoos como siempre a trav\u00e9s de WhatsApp o llamada de tel\u00e9fono (esperamos que el nuevo n\u00famero est\u00e9 activo antes del 1 de noviembre de 2023). Mientras&#8230; \u00a1Apunta el nuevo n\u00famero&#8230; y perdona si no has podido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"og:description\" content=\"Tras diversos problemas con el proveedor de telefon\u00eda m\u00f3vil, nos hemos visto obligadas a cambiar de n\u00famero para seguir atendi\u00e9ndoos como siempre a trav\u00e9s de WhatsApp o llamada de tel\u00e9fono (esperamos que el nuevo n\u00famero est\u00e9 activo antes del 1 de noviembre de 2023). Mientras&#8230; \u00a1Apunta el nuevo n\u00famero&#8230; y perdona si no has podido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T12:02:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T08:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"Nuevo tel\u00e9fono de la AMPA\",\"datePublished\":\"2023-10-30T12:02:25+00:00\",\"dateModified\":\"2024-06-06T08:32:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/\"},\"wordCount\":146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Nuevo-telefono-scaled.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/\",\"name\":\"Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Nuevo-telefono-scaled.jpg\",\"datePublished\":\"2023-10-30T12:02:25+00:00\",\"dateModified\":\"2024-06-06T08:32:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Nuevo-telefono-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Nuevo-telefono-scaled.jpg\",\"width\":2560,\"height\":1613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/30\\\/nuevo-telefono-ampa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo tel\u00e9fono de la AMPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla","og_description":"Tras diversos problemas con el proveedor de telefon\u00eda m\u00f3vil, nos hemos visto obligadas a cambiar de n\u00famero para seguir atendi\u00e9ndoos como siempre a trav\u00e9s de WhatsApp o llamada de tel\u00e9fono (esperamos que el nuevo n\u00famero est\u00e9 activo antes del 1 de noviembre de 2023). Mientras&#8230; \u00a1Apunta el nuevo n\u00famero&#8230; y perdona si no has podido [&hellip;]","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2023-10-30T12:02:25+00:00","article_modified_time":"2024-06-06T08:32:30+00:00","og_image":[{"width":2560,"height":1613,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"Nuevo tel\u00e9fono de la AMPA","datePublished":"2023-10-30T12:02:25+00:00","dateModified":"2024-06-06T08:32:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/"},"wordCount":146,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/","name":"Nuevo tel\u00e9fono de la AMPA - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg","datePublished":"2023-10-30T12:02:25+00:00","dateModified":"2024-06-06T08:32:30+00:00","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Nuevo-telefono-scaled.jpg","width":2560,"height":1613},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/30\/nuevo-telefono-ampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"Nuevo tel\u00e9fono de la AMPA"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1696"}],"version-history":[{"count":5,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1696\/revisions"}],"predecessor-version":[{"id":1789,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1696\/revisions\/1789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1788"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}