{"id":1464,"date":"2013-12-19T23:30:00","date_gmt":"2013-12-19T22:30:00","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1464"},"modified":"2023-10-23T23:48:37","modified_gmt":"2023-10-23T21:48:37","slug":"hemeroampa-dia-del-senderismo-2013-sierra-de-aracena","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/","title":{"rendered":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena"},"content":{"rendered":"\n<p>El 9 de noviembre nos fuimos de excursi\u00f3n a la Sierra de Aracena, aprovechando que el tiempo mejor\u00f3 y pudimos organizar el D\u00eda del Senderismo previsto inicialmente para el 19 de octubre. Nos hizo un d\u00eda magn\u00edfico, si acaso un poco corto porque en esta \u00e9poca del a\u00f1o ya el sol se esconde pronto, pero lo aprovechamos bien. Recorrimos el sendero hasta Valdelarco, recogiendo de camino una buena cantidad de casta\u00f1as, repusimos fuerzas en el pueblo, y volvimos hacia el \u00e1rea recreativa justo a tiempo para comer.<\/p>\n\n\n\n<p>Os damos las gracias a todos por participar, y esperamos veros de nuevo en la pr\u00f3xima excursi\u00f3n que ya andamos planeando. Por supuesto admitimos ideas, as\u00ed que si ten\u00e9is alguna sugerencia, no dej\u00e9is de hac\u00e9rnosla llegar.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/1aZQmNLK2QWRXhel32yDx1EHjuEvRltWvTYDBSN0fL_YBXoAVbg.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"274\" src=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/1aZQmNLK2QWRXhel32yDx1EHjuEvRltWvTYDBSN0fL_YBXoAVbg.jpg\" alt=\"\" class=\"wp-image-1480\" style=\"aspect-ratio:2.335766423357664;width:823px;height:auto\" srcset=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/1aZQmNLK2QWRXhel32yDx1EHjuEvRltWvTYDBSN0fL_YBXoAVbg.jpg 640w, https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/1aZQmNLK2QWRXhel32yDx1EHjuEvRltWvTYDBSN0fL_YBXoAVbg-480x206.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\u00a1\u00a1AY\u00daDANOS A CRECER COMO AMPA!!<\/strong>&nbsp;<strong>\u00a1\u00a1As\u00f3ciate!!<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\">Por una cuota de 35\u20ac anuales por familia, mejora tu colegio, conoce informaci\u00f3n \u00fatil como esta y obt\u00e9n beneficios y descuentos.<\/a><\/strong>&nbsp;<a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/strong><\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tambi\u00e9n puedes participar, a trav\u00e9s del voluntariado, apoyando las actividades que desarrollamos o planteando nuevas ideas que quieras poner en marcha junto a nuestro equipo.<\/a><\/strong>&nbsp;<strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/a><\/strong><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El 9 de noviembre nos fuimos de excursi\u00f3n a la Sierra de Aracena, aprovechando que el tiempo mejor\u00f3 y pudimos organizar el D\u00eda del Senderismo previsto inicialmente para el 19 de octubre. Nos hizo un d\u00eda magn\u00edfico, si acaso un poco corto porque en esta \u00e9poca del a\u00f1o ya el sol se esconde pronto, pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"og:description\" content=\"El 9 de noviembre nos fuimos de excursi\u00f3n a la Sierra de Aracena, aprovechando que el tiempo mejor\u00f3 y pudimos organizar el D\u00eda del Senderismo previsto inicialmente para el 19 de octubre. Nos hizo un d\u00eda magn\u00edfico, si acaso un poco corto porque en esta \u00e9poca del a\u00f1o ya el sol se esconde pronto, pero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-19T22:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T21:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png\" \/>\n\t<meta property=\"og:image:width\" content=\"476\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena\",\"datePublished\":\"2013-12-19T22:30:00+00:00\",\"dateModified\":\"2023-10-23T21:48:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Dia-del-senderismo-2013.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/\",\"name\":\"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Dia-del-senderismo-2013.png\",\"datePublished\":\"2013-12-19T22:30:00+00:00\",\"dateModified\":\"2023-10-23T21:48:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Dia-del-senderismo-2013.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Dia-del-senderismo-2013.png\",\"width\":476,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2013\\\/12\\\/19\\\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/","og_locale":"es_ES","og_type":"article","og_title":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla","og_description":"El 9 de noviembre nos fuimos de excursi\u00f3n a la Sierra de Aracena, aprovechando que el tiempo mejor\u00f3 y pudimos organizar el D\u00eda del Senderismo previsto inicialmente para el 19 de octubre. Nos hizo un d\u00eda magn\u00edfico, si acaso un poco corto porque en esta \u00e9poca del a\u00f1o ya el sol se esconde pronto, pero [&hellip;]","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2013-12-19T22:30:00+00:00","article_modified_time":"2023-10-23T21:48:37+00:00","og_image":[{"width":476,"height":300,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena","datePublished":"2013-12-19T22:30:00+00:00","dateModified":"2023-10-23T21:48:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/","name":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png","datePublished":"2013-12-19T22:30:00+00:00","dateModified":"2023-10-23T21:48:37+00:00","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Dia-del-senderismo-2013.png","width":476,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2013\/12\/19\/hemeroampa-dia-del-senderismo-2013-sierra-de-aracena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"HemeroAMPA: D\u00eda del Senderismo 2013. Sierra de Aracena"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":2,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1481,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1465"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}