{"id":1417,"date":"2023-10-23T22:11:08","date_gmt":"2023-10-23T20:11:08","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1417"},"modified":"2023-10-23T22:11:09","modified_gmt":"2023-10-23T20:11:09","slug":"pospuesta-la-fiesta-del-deporte-del-1-de-noviembre","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/","title":{"rendered":"Pospuesta la fiesta del deporte del 1 de noviembre"},"content":{"rendered":"\n<p>Debido a la previsi\u00f3n de mal tiempo, hemos tenido que tomar la decisi\u00f3n de posponer a una nueva fecha para poder disfrutar de nuestro tradicional d\u00eda del deporte y encuentro. <\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\u00a1\u00a1ESTAD ATENTAS Y ATENTOS A LA WEB Y A LOS GRUPOS DE WHATSAPP DEL COLE PARA CONOCER NUEVAS FECHAS Y ACTIVIDADES!!<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Mientras, recuerda que<strong>\u00a0este a\u00f1o,  jugamos a la loter\u00eda de Navidad, y que\u2026 \u00a1\u00a1\u00a1PUEDE TOCAR AQU\u00cd!!!!<\/strong>\u00a0\u00a1\u00a1JUEGA A LA AMPAloter\u00eda!!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"522\" height=\"309\" src=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-01-at-18.55.42.png\" alt=\"\" class=\"wp-image-1395\" srcset=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-01-at-18.55.42.png 522w, https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-01-at-18.55.42-480x284.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 522px, 100vw\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u00a1\u00a1AY\u00daDANOS A CRECER COMO AMPA!!<\/strong>&nbsp;<strong>\u00a1\u00a1As\u00f3ciate!!<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\">Por una cuota de 35\u20ac anuales por familia, mejora tu colegio, conoce informaci\u00f3n \u00fatil como esta y obt\u00e9n beneficios y descuentos.<\/a><\/strong>&nbsp;<a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/strong><\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tambi\u00e9n puedes participar, a trav\u00e9s del voluntariado, apoyando las actividades que desarrollamos o planteando nuevas ideas que quieras poner en marcha junto a nuestro equipo.<\/a><\/strong>&nbsp;<strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a la previsi\u00f3n de mal tiempo, hemos tenido que tomar la decisi\u00f3n de posponer a una nueva fecha para poder disfrutar de nuestro tradicional d\u00eda del deporte y encuentro. \u00a1\u00a1ESTAD ATENTAS Y ATENTOS A LA WEB Y A LOS GRUPOS DE WHATSAPP DEL COLE PARA CONOCER NUEVAS FECHAS Y ACTIVIDADES!!<\/p>\n","protected":false},"author":1,"featured_media":1419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[14,11,28,30],"class_list":["post-1417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-actividades","tag-curso-2022-23","tag-dia-del-deporte","tag-tiempo-libre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"og:description\" content=\"Debido a la previsi\u00f3n de mal tiempo, hemos tenido que tomar la decisi\u00f3n de posponer a una nueva fecha para poder disfrutar de nuestro tradicional d\u00eda del deporte y encuentro. \u00a1\u00a1ESTAD ATENTAS Y ATENTOS A LA WEB Y A LOS GRUPOS DE WHATSAPP DEL COLE PARA CONOCER NUEVAS FECHAS Y ACTIVIDADES!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T20:11:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T20:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"Pospuesta la fiesta del deporte del 1 de noviembre\",\"datePublished\":\"2023-10-23T20:11:08+00:00\",\"dateModified\":\"2023-10-23T20:11:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/\"},\"wordCount\":161,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Cancelada-fiesta-del-deporte.png\",\"keywords\":[\"actividades\",\"Curso 2022\\\/23\",\"D\u00eda del deporte\",\"Tiempo libre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/\",\"name\":\"Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Cancelada-fiesta-del-deporte.png\",\"datePublished\":\"2023-10-23T20:11:08+00:00\",\"dateModified\":\"2023-10-23T20:11:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Cancelada-fiesta-del-deporte.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Cancelada-fiesta-del-deporte.png\",\"width\":952,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/10\\\/23\\\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pospuesta la fiesta del deporte del 1 de noviembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/","og_locale":"es_ES","og_type":"article","og_title":"Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla","og_description":"Debido a la previsi\u00f3n de mal tiempo, hemos tenido que tomar la decisi\u00f3n de posponer a una nueva fecha para poder disfrutar de nuestro tradicional d\u00eda del deporte y encuentro. \u00a1\u00a1ESTAD ATENTAS Y ATENTOS A LA WEB Y A LOS GRUPOS DE WHATSAPP DEL COLE PARA CONOCER NUEVAS FECHAS Y ACTIVIDADES!!","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2023-10-23T20:11:08+00:00","article_modified_time":"2023-10-23T20:11:09+00:00","og_image":[{"width":952,"height":600,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"Pospuesta la fiesta del deporte del 1 de noviembre","datePublished":"2023-10-23T20:11:08+00:00","dateModified":"2023-10-23T20:11:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/"},"wordCount":161,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png","keywords":["actividades","Curso 2022\/23","D\u00eda del deporte","Tiempo libre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/","name":"Pospuesta la fiesta del deporte del 1 de noviembre - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png","datePublished":"2023-10-23T20:11:08+00:00","dateModified":"2023-10-23T20:11:09+00:00","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/10\/Cancelada-fiesta-del-deporte.png","width":952,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/10\/23\/pospuesta-la-fiesta-del-deporte-del-1-de-noviembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"Pospuesta la fiesta del deporte del 1 de noviembre"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":1,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"predecessor-version":[{"id":1420,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1417\/revisions\/1420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1419"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}