{"id":1151,"date":"2023-01-11T11:02:34","date_gmt":"2023-01-11T10:02:34","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1151"},"modified":"2024-06-06T10:58:00","modified_gmt":"2024-06-06T08:58:00","slug":"asamblea-ordinaria-2023","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/","title":{"rendered":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA"},"content":{"rendered":"\n<p>La AMPA del Colegio San Bernardo os informa de que nuestra pr\u00f3xima asamblea ordinaria de la Asociaci\u00f3n se celebrar\u00e1 en el comedor del colegio. el pr\u00f3ximo d\u00eda <strong>17 de Enero de 2023 <\/strong>a las <strong>16.45 horas <\/strong>en primera convocatoria y <strong>17.00 horas <\/strong>en segunda convocatoria, con el siguiente <strong>orden del d\u00eda<\/strong>:<\/p>\n\n\n\n<!--more-->\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Lectura y aprobaci\u00f3n, si procede, del acta de la Asamblea anterior.<\/li>\n\n\n\n<li>Examen y aprobaci\u00f3n, si procede, del estado de cuentas del ejercicio anterior.<\/li>\n\n\n\n<li>Examen y aprobaci\u00f3n, si procede, de los presupuestos del ejercicio 2023.<\/li>\n\n\n\n<li>Examen de la memoria de actividades y aprobaci\u00f3n, si procede, de la gesti\u00f3n de la Junta Directiva.<\/li>\n\n\n\n<li>Aprobaci\u00f3n, si procede, del programa de actividades para el ejercicio 2023.Ruegos y Preguntas.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-large-font-size\"><strong>\u00a1OS ESPERAMOS!<\/strong><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/CONVOCATORIA-DE-ASAMBLEA-GENERAL-ORDINARIA-2023-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Para descargar documento oficial de la convocatoria, pincha AQUI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La AMPA del Colegio San Bernardo os informa de que nuestra pr\u00f3xima asamblea ordinaria de la Asociaci\u00f3n se celebrar\u00e1 en el comedor del colegio. el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 16.45 horas en primera convocatoria y 17.00 horas en segunda convocatoria, con el siguiente orden del d\u00eda:<\/p>\n","protected":false},"author":1,"featured_media":1807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"description\" content=\"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"og:description\" content=\"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T10:02:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T08:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1488\" \/>\n\t<meta property=\"og:image:height\" content=\"938\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA\",\"datePublished\":\"2023-01-11T10:02:34+00:00\",\"dateModified\":\"2024-06-06T08:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/\"},\"wordCount\":137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Asamblea-23.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/\",\"name\":\"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Asamblea-23.jpg\",\"datePublished\":\"2023-01-11T10:02:34+00:00\",\"dateModified\":\"2024-06-06T08:58:00+00:00\",\"description\":\"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Asamblea-23.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Asamblea-23.jpg\",\"width\":1488,\"height\":938},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2023\\\/01\\\/11\\\/asamblea-ordinaria-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla","description":"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/","og_locale":"es_ES","og_type":"article","og_title":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla","og_description":"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2023-01-11T10:02:34+00:00","article_modified_time":"2024-06-06T08:58:00+00:00","og_image":[{"width":1488,"height":938,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA","datePublished":"2023-01-11T10:02:34+00:00","dateModified":"2024-06-06T08:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/"},"wordCount":137,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/","name":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg","datePublished":"2023-01-11T10:02:34+00:00","dateModified":"2024-06-06T08:58:00+00:00","description":"Nuestra pr\u00f3xima asamblea de la AMPA se celebrar\u00e1 el pr\u00f3ximo d\u00eda 17 de Enero de 2023 a las 17.00 horas en el colegio. \u00a1Os esperamos!","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2023\/01\/Asamblea-23.jpg","width":1488,"height":938},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2023\/01\/11\/asamblea-ordinaria-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"CONVOCATORIA DE ASAMBLEA GENERAL ORDINARIA"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":7,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":1163,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions\/1163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1807"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}