{"id":1059,"date":"2022-09-28T16:53:45","date_gmt":"2022-09-28T14:53:45","guid":{"rendered":"https:\/\/www.ampasanbernardo.es\/?p=1059"},"modified":"2022-09-28T17:09:45","modified_gmt":"2022-09-28T15:09:45","slug":"dia-deporte-familia-2022","status":"publish","type":"post","link":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/","title":{"rendered":"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte"},"content":{"rendered":"\n<p>El pr\u00f3ximo mi\u00e9rcoles 12 de octubre desde la AMPA del colegio San Bernardo te invitamos a que particip\u00e9is en el \u201c<strong>D\u00cdA DEL DEPORTE EN FAMILIA 2022<\/strong>\u201d que estamos organizado.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Tras la pandemia, y despu\u00e9s de un tiempo en el que hemos tenido muy limitado el contacto, queremos retomar los espacios de encuentro entre las familias que formamos parte del Colegio San Bernardo y hemos pensado que una buena idea, es retomar el d\u00eda del Deporte que tantos a\u00f1os hemos organizado.<\/p>\n\n\n\n<p>Un d\u00eda del deporte en el que nos divertiremos junto a nuestros hijos e hijas, haciendo deporte, escuchando m\u00fasica y con muchas m\u00e1s actividades que os iremos contando en los pr\u00f3ximos d\u00edas.<\/p>\n\n\n\n<p>Tambi\u00e9n, habr\u00e1 una barra en la que poder comprar comida y bebida para que no tengamos que preocuparnos por nada. La empresa que la monta ceder\u00e1 un porcentaje de los beneficios a la AMPA, que lo reinvertir\u00e1 en nuevas actividades y equipamientos para el colegio.<\/p>\n\n\n\n<p><strong>\u00a1RESERVA EL D\u00cdA Y PRESTA ATENCI\u00d3N A NUESTRA WEB Y AL WHATSAPP! \u00a1TE MANDAREMOS TODA LA INFORMACI\u00d3N PR\u00d3XIMAMENTE!<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u00a1\u00a1AY\u00daDANOS A CRECER COMO AMPA!!  <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\">Por una cuota de 30\u20ac anuales por familia, mejora tu colegio y obt\u00e9n beneficios y descuentos.<\/a><\/strong> <a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/apuntate\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tambi\u00e9n puedes participar, a trav\u00e9s del voluntariado, apoyando las actividades que desarrollamos o planteando nuevas ideas que quieras poner en marcha junto a nuestro equipo.<\/a><\/strong> <strong><a href=\"https:\/\/www.ampasanbernardo.es\/index.php\/participa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Para m\u00e1s informaci\u00f3n, haz CLICK AQU\u00cd<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo mi\u00e9rcoles 12 de octubre desde la AMPA del colegio San Bernardo te invitamos a que particip\u00e9is en el \u201cD\u00cdA DEL DEPORTE EN FAMILIA 2022\u201d que estamos organizado.<\/p>\n","protected":false},"author":1,"featured_media":1069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[14,11,28,29,30],"class_list":["post-1059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-actividades","tag-curso-2022-23","tag-dia-del-deporte","tag-ocio","tag-tiempo-libre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte - AMPA San Bernardo - Sevilla<\/title>\n<meta name=\"description\" content=\"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00, la AMPA del colegio San Bernardo, ha organizado el &quot;D\u00cdA DEL DEPORTE EN FAMILIA 2022&quot;. \u00a1Participa!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda del deporte 2022. AMPA San Bernardo\" \/>\n<meta property=\"og:description\" content=\"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00 la AMPA del colegio San Bernardo, ha organizado el &quot;D\u00cdA DEL DEPORTE EN FAMILIA 2022&quot;. \u00a1Participa!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"AMPA San Bernardo - Sevilla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ampasanbernardosevilla\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T14:53:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T15:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"475\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00eda del deporte 2022. AMPA San Bernardo\" \/>\n<meta name=\"twitter:description\" content=\"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00 la AMPA del colegio San Bernardo, ha organizado el &quot;D\u00cdA DEL DEPORTE EN FAMILIA 2022&quot;. \u00a1Participa!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\"},\"headline\":\"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte\",\"datePublished\":\"2022-09-28T14:53:45+00:00\",\"dateModified\":\"2022-09-28T15:09:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-deporte-2022.4.png\",\"keywords\":[\"actividades\",\"Curso 2022\\\/23\",\"D\u00eda del deporte\",\"ocio\",\"Tiempo libre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/\",\"name\":\"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte - AMPA San Bernardo - Sevilla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-deporte-2022.4.png\",\"datePublished\":\"2022-09-28T14:53:45+00:00\",\"dateModified\":\"2022-09-28T15:09:45+00:00\",\"description\":\"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00, la AMPA del colegio San Bernardo, ha organizado el \\\"D\u00cdA DEL DEPORTE EN FAMILIA 2022\\\". \u00a1Participa!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-deporte-2022.4.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-deporte-2022.4.png\",\"width\":950,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/2022\\\/09\\\/28\\\/dia-deporte-familia-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#website\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"name\":\"AMPA San Bernardo - Sevilla\",\"description\":\"P\u00e1gina web de la AMPA del colegio San Bernardo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#organization\",\"name\":\"AMPA San Bernardo - Sevilla\",\"alternateName\":\"AMPA San Bernardo\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png\",\"width\":200,\"height\":196,\"caption\":\"AMPA San Bernardo - Sevilla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ampasanbernardosevilla\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/#\\\/schema\\\/person\\\/0e584dea70d175a88a65dd99679ae206\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.ampasanbernardo.es\"],\"url\":\"https:\\\/\\\/www.ampasanbernardo.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte - AMPA San Bernardo - Sevilla","description":"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00, la AMPA del colegio San Bernardo, ha organizado el \"D\u00cdA DEL DEPORTE EN FAMILIA 2022\". \u00a1Participa!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda del deporte 2022. AMPA San Bernardo","og_description":"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00 la AMPA del colegio San Bernardo, ha organizado el \"D\u00cdA DEL DEPORTE EN FAMILIA 2022\". \u00a1Participa!","og_url":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/","og_site_name":"AMPA San Bernardo - Sevilla","article_publisher":"https:\/\/www.facebook.com\/ampasanbernardosevilla\/","article_published_time":"2022-09-28T14:53:45+00:00","article_modified_time":"2022-09-28T15:09:45+00:00","og_image":[{"width":475,"height":300,"url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_title":"D\u00eda del deporte 2022. AMPA San Bernardo","twitter_description":"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00 la AMPA del colegio San Bernardo, ha organizado el \"D\u00cdA DEL DEPORTE EN FAMILIA 2022\". \u00a1Participa!","twitter_image":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.png","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#article","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/"},"author":{"name":"admin","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206"},"headline":"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte","datePublished":"2022-09-28T14:53:45+00:00","dateModified":"2022-09-28T15:09:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.4.png","keywords":["actividades","Curso 2022\/23","D\u00eda del deporte","ocio","Tiempo libre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/","url":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/","name":"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte - AMPA San Bernardo - Sevilla","isPartOf":{"@id":"https:\/\/www.ampasanbernardo.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.4.png","datePublished":"2022-09-28T14:53:45+00:00","dateModified":"2022-09-28T15:09:45+00:00","description":"El mi\u00e9rcoles 12 de octubre de 11.00 a 18.00, la AMPA del colegio San Bernardo, ha organizado el \"D\u00cdA DEL DEPORTE EN FAMILIA 2022\". \u00a1Participa!","breadcrumb":{"@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#primaryimage","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.4.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/Dia-del-deporte-2022.4.png","width":950,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.ampasanbernardo.es\/index.php\/2022\/09\/28\/dia-deporte-familia-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ampasanbernardo.es\/"},{"@type":"ListItem","position":2,"name":"Reserva el d\u00eda: 12 de octubre. D\u00eda del deporte"}]},{"@type":"WebSite","@id":"https:\/\/www.ampasanbernardo.es\/#website","url":"https:\/\/www.ampasanbernardo.es\/","name":"AMPA San Bernardo - Sevilla","description":"P\u00e1gina web de la AMPA del colegio San Bernardo.","publisher":{"@id":"https:\/\/www.ampasanbernardo.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ampasanbernardo.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ampasanbernardo.es\/#organization","name":"AMPA San Bernardo - Sevilla","alternateName":"AMPA San Bernardo","url":"https:\/\/www.ampasanbernardo.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","contentUrl":"https:\/\/www.ampasanbernardo.es\/wp-content\/uploads\/2022\/09\/cropped-cropped-Logo-para-estudio-de-tatuaje-minimalista-circular-en-tonos-gris-y-blanco.-1.png","width":200,"height":196,"caption":"AMPA San Bernardo - Sevilla"},"image":{"@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ampasanbernardosevilla\/"]},{"@type":"Person","@id":"https:\/\/www.ampasanbernardo.es\/#\/schema\/person\/0e584dea70d175a88a65dd99679ae206","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52afccea388921dc7c2f87999c39cf39f1ddfc4e5be42b3e79ef082fac5b767?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.ampasanbernardo.es"],"url":"https:\/\/www.ampasanbernardo.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/comments?post=1059"}],"version-history":[{"count":4,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1059\/revisions"}],"predecessor-version":[{"id":1066,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/posts\/1059\/revisions\/1066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media\/1069"}],"wp:attachment":[{"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/media?parent=1059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/categories?post=1059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ampasanbernardo.es\/index.php\/wp-json\/wp\/v2\/tags?post=1059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}